{"id":3,"date":"2025-05-27T14:06:25","date_gmt":"2025-05-27T14:06:25","guid":{"rendered":"https:\/\/valbare.it\/?page_id=3"},"modified":"2025-06-18T11:52:13","modified_gmt":"2025-06-18T11:52:13","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/valbare.it\/fr\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<section class=\"bde-section-3-102 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><\/div>\n<\/section><section class=\"bde-section-3-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-rich-text-3-101 bde-rich-text breakdance-rich-text-styles\">\n<h1 data-start=\"462\" data-end=\"489\">Informativa sulla Privacy<\/h1>\n<h2 data-start=\"491\" data-end=\"521\">1. Titolare del trattamento<\/h2>\n<p data-start=\"523\" data-end=\"562\">Il titolare del trattamento dei dati \u00e8:<\/p>\n<p data-start=\"564\" data-end=\"742\"><strong data-start=\"564\" data-end=\"593\">Valbar\u00e8 di Monica Moretto<\/strong><br data-start=\"593\" data-end=\"596\" \/>Sede legale: 32, Via Case Fossa 31010 Fregona - Italia<br data-start=\"638\" data-end=\"641\" \/>Email: <a class=\"cursor-pointer\" rel=\"noopener\">info@valbare.it<\/a><br data-start=\"700\" data-end=\"703\" \/>Telefono: +39 324 66 13 260<\/p>\n<h2 data-start=\"744\" data-end=\"776\">2. Tipologia di dati trattati<\/h2>\n<p data-start=\"778\" data-end=\"842\">Raccogliamo e trattiamo le seguenti categorie di dati personali:<\/p>\n<ul data-start=\"844\" data-end=\"1221\">\n<li data-start=\"844\" data-end=\"961\">\n<p data-start=\"846\" data-end=\"961\"><strong data-start=\"846\" data-end=\"879\">Dati anagrafici e di contatto<\/strong>: nome, cognome, email, telefono, indirizzo (in caso di prenotazioni o richieste).<\/p>\n<\/li>\n<li data-start=\"962\" data-end=\"1077\">\n<p data-start=\"964\" data-end=\"1077\"><strong data-start=\"964\" data-end=\"980\">Dati tecnici<\/strong>: indirizzi IP, tipo di browser, dati di navigazione raccolti tramite cookie tecnici e analitici.<\/p>\n<\/li>\n<li data-start=\"1078\" data-end=\"1221\">\n<p data-start=\"1080\" data-end=\"1221\"><strong data-start=\"1080\" data-end=\"1112\">Dati forniti volontariamente<\/strong> tramite moduli (es. modulo contatti, prenotazioni camere, richieste al ristorante, iscrizione a newsletter).<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"1223\" data-end=\"1253\">3. Finalit\u00e0 del trattamento<\/h2>\n<p data-start=\"1255\" data-end=\"1311\">I dati personali sono raccolti per le seguenti finalit\u00e0:<\/p>\n<ul data-start=\"1313\" data-end=\"1640\">\n<li data-start=\"1313\" data-end=\"1397\">\n<p data-start=\"1315\" data-end=\"1397\">Rispondere a richieste di informazioni inviate tramite i moduli presenti sul sito.<\/p>\n<\/li>\n<li data-start=\"1398\" data-end=\"1484\">\n<p data-start=\"1400\" data-end=\"1484\">Gestire le prenotazioni effettuate online tramite il sistema integrato (es. Smoobu).<\/p>\n<\/li>\n<li data-start=\"1485\" data-end=\"1564\">\n<p data-start=\"1487\" data-end=\"1564\">Inviare aggiornamenti via email o newsletter, solo previo consenso esplicito.<\/p>\n<\/li>\n<li data-start=\"1565\" data-end=\"1640\">\n<p data-start=\"1567\" data-end=\"1640\">Analisi anonima del traffico per migliorare l\u2019esperienza utente sul sito.<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"1642\" data-end=\"1678\">4. Base giuridica del trattamento<\/h2>\n<p data-start=\"1680\" data-end=\"1718\">I dati vengono trattati sulla base di:<\/p>\n<ul data-start=\"1720\" data-end=\"2017\">\n<li data-start=\"1720\" data-end=\"1820\">\n<p data-start=\"1722\" data-end=\"1820\"><strong data-start=\"1722\" data-end=\"1777\">Esecuzione di un contratto o misure precontrattuali<\/strong> (es. prenotazioni o richieste specifiche).<\/p>\n<\/li>\n<li data-start=\"1821\" data-end=\"1879\">\n<p data-start=\"1823\" data-end=\"1879\"><strong data-start=\"1823\" data-end=\"1845\">Consenso esplicito<\/strong> (es. iscrizione alla newsletter).<\/p>\n<\/li>\n<li data-start=\"1880\" data-end=\"2017\">\n<p data-start=\"1882\" data-end=\"2017\"><strong data-start=\"1882\" data-end=\"1918\">Legittimo interesse del titolare<\/strong> a migliorare la navigazione e la qualit\u00e0 del sito (es. cookies tecnici e statistici anonimizzati).<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"2019\" data-end=\"2049\">5. Modalit\u00e0 del trattamento<\/h2>\n<p data-start=\"2051\" data-end=\"2246\">Il trattamento avviene con strumenti elettronici e cartacei, nel rispetto delle misure di sicurezza previste dal GDPR.<br data-start=\"2169\" data-end=\"2172\" \/>I dati non saranno in alcun modo diffusi o ceduti a terzi non autorizzati.<\/p>\n<h2 data-start=\"2248\" data-end=\"2274\">6. Destinatari dei dati<\/h2>\n<p data-start=\"2276\" data-end=\"2311\">I dati potranno essere trattati da:<\/p>\n<ul data-start=\"2313\" data-end=\"2567\">\n<li data-start=\"2313\" data-end=\"2375\">\n<p data-start=\"2315\" data-end=\"2375\">Collaboratori interni e soggetti autorizzati al trattamento.<\/p>\n<\/li>\n<li data-start=\"2376\" data-end=\"2510\">\n<p data-start=\"2378\" data-end=\"2510\">Fornitori di servizi web (es. hosting, gestionali di prenotazione, plugin WordPress), nominati responsabili esterni del trattamento.<\/p>\n<\/li>\n<li data-start=\"2511\" data-end=\"2567\">\n<p data-start=\"2513\" data-end=\"2567\">Autorit\u00e0 competenti, solo in caso di obbligo di legge.<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"2569\" data-end=\"2599\">7. Periodo di conservazione<\/h2>\n<ul data-start=\"2601\" data-end=\"2912\">\n<li data-start=\"2601\" data-end=\"2676\">\n<p data-start=\"2603\" data-end=\"2676\">I dati raccolti per finalit\u00e0 contrattuali saranno conservati per 10 anni.<\/p>\n<\/li>\n<li data-start=\"2677\" data-end=\"2785\">\n<p data-start=\"2679\" data-end=\"2785\">I dati raccolti tramite modulo contatti o newsletter saranno conservati fino a richiesta di cancellazione.<\/p>\n<\/li>\n<li data-start=\"2786\" data-end=\"2912\">\n<p data-start=\"2788\" data-end=\"2912\">I dati tecnici raccolti tramite cookie saranno conservati secondo la durata prevista da ciascun cookie (vedi Cookie Policy).<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"2914\" data-end=\"2944\">8. Diritti dell\u2019interessato<\/h2>\n<p data-start=\"2946\" data-end=\"2961\">Hai diritto di:<\/p>\n<ul data-start=\"2963\" data-end=\"3211\">\n<li data-start=\"2963\" data-end=\"2997\">\n<p data-start=\"2965\" data-end=\"2997\">Accedere ai tuoi dati personali.<\/p>\n<\/li>\n<li data-start=\"2998\" data-end=\"3073\">\n<p data-start=\"3000\" data-end=\"3073\">Chiedere la rettifica, la cancellazione o la limitazione del trattamento.<\/p>\n<\/li>\n<li data-start=\"3074\" data-end=\"3143\">\n<p data-start=\"3076\" data-end=\"3143\">Opporti al trattamento o revocare il consenso in qualsiasi momento.<\/p>\n<\/li>\n<li data-start=\"3144\" data-end=\"3211\">\n<p data-start=\"3146\" data-end=\"3211\">Proporre reclamo al Garante per la Protezione dei Dati Personali.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3213\" data-end=\"3301\">Puoi esercitare i tuoi diritti scrivendo a <strong data-start=\"3256\" data-end=\"3300\">[inserire email, es. <a class=\"cursor-pointer\" rel=\"noopener\">privacy@valbare.it<\/a>]<\/strong>.<\/p>\n<h2 data-start=\"3303\" data-end=\"3344\">9. Modifiche alla presente informativa<\/h2>\n<p data-start=\"3346\" data-end=\"3464\">Valbar\u00e8 si riserva il diritto di aggiornare la presente informativa. Le modifiche saranno pubblicate su questa pagina.<\/p>\n<h3 data-start=\"3471\" data-end=\"3526\">Ultimo aggiornamento: [inserire data pubblicazione]<\/h3>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Informativa sulla Privacy 1. Titolare del trattamento Il titolare del trattamento dei dati \u00e8: Valbar\u00e8 di Monica MorettoSede legale: 32, Via Case Fossa 31010 Fregona &#8211; ItaliaEmail: info@valbare.itTelefono: +39 324 66 13 260 2. Tipologia di dati trattati Raccogliamo e trattiamo le seguenti categorie di dati personali: Dati anagrafici e di contatto: nome, cognome, email, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":4,"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":386,"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/pages\/3\/revisions\/386"}],"wp:attachment":[{"href":"https:\/\/valbare.it\/fr\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}